{"id":20841,"date":"2024-09-25T11:49:57","date_gmt":"2024-09-25T11:49:57","guid":{"rendered":"https:\/\/mousefreemarion.org\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\/"},"modified":"2024-09-25T11:49:57","modified_gmt":"2024-09-25T11:49:57","slug":"suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen","status":"publish","type":"post","link":"https:\/\/mousefreemarion.org\/de\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\/","title":{"rendered":"S\u00fcdafrika wird das Albatros- und Sturmvogelabkommen bei der \u00dcberarbeitung seiner Best-Practice-Richtlinien f\u00fcr die Ausrottung eingeschleppter S\u00e4ugetiere auf Inseln unterst\u00fctzen"},"content":{"rendered":"<p>Bild oben:  <em>Dieses Jungtier des Hellmantelalbatros hat die n\u00e4chtlichen Angriffe von eingef\u00fchrten Hausm\u00e4usen auf Marion Island nicht \u00fcberlebt.<br \/>\nGraukopf-, Ru\u00df- und Wanderalbatrosse sind alle der gleichen Bedrohung ausgesetzt; Foto von Peter Ryan <\/em>  Die 14. Sitzung (AC14) des internationalen \u00dcbereinkommens zur Erhaltung der Albatrosse und Sturmv\u00f6gel (<strong><a href=\"https:\/\/www.acap.aq\" target=\"_blank\" rel=\"noopener\">ACAP<\/a><\/strong>) wurde vom 12. bis 16. August 2024 in Lima, Peru, abgehalten.<br \/>\nBei der Pr\u00fcfung des <strong><a href=\"https:\/\/www.acap.aq\/documents\/advisory-committee\/ac14\/ac14-meeting-documents\/4834-ac14-doc-14\/file\" target=\"_blank\" rel=\"noopener\">Bericht<\/a><\/strong> der Arbeitsgruppe f\u00fcr Population und Erhaltungszustand (<strong><a href=\"https:\/\/www.acap.aq\/documents\/working-groups\/population-and-conservation-status-working-group\" target=\"_blank\" rel=\"noopener\">PaCSWG<\/a><\/strong>), die in der Woche zuvor getagt hatte, stimmte der Ausschuss zu, dass die ACAP Best-Practice <strong><a href=\"https:\/\/www.acap.aq\/resources\/acap-conservation-guidelines\/2179-eradication-guidelines\/file\" target=\"_blank\" rel=\"noopener\">Leitlinien f\u00fcr die Ausrottung eingeschleppter S\u00e4ugetiere aus Brutgebieten von ACAP-gelisteten Seev\u00f6geln<\/a><\/strong>die zuletzt im September 2019 aktualisiert wurden, im Lichte neuer Erkenntnisse aus den j\u00fcngsten Versuchen, Hausm\u00e4use <em>Mus musculus <\/em>von Inseln auszurotten, \u00fcberarbeitet werden sollten, wobei insbesondere die gescheiterten Ausrottungen von Hausm\u00e4usen auf Gough Island und Sand Island, Midway Atoll, zu beachten sind.<br \/>\nDer Beratende Ausschuss stimmte zu, diese Aufgabe in sein Arbeitsprogramm f\u00fcr 2023-2025 aufzunehmen (  <strong><a href=\"https:\/\/www.acap.aq\/documents\/advisory-committee\/ac14\/ac14-meeting-documents\/4758-ac14-doc-22-ac-work-programme-2023-2025\/file\" target=\"_blank\" rel=\"noopener\"><g id=\"gid_0\">AC 14 Doc.<br \/>\n22<\/g> <\/a><\/strong>  und <strong><a href=\"https:\/\/www.acap.aq\/documents\/advisory-committee\/ac14\/4851-ac14-report\/file\" target=\"_blank\" rel=\"noopener\">Anhang 5 Aufgabe 2.9 des AC14-Berichts<\/a><\/strong>).  <div id=\"attachment_20825\" style=\"width: 810px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-20825\" class=\"wp-image-20825 size-fusion-800\" src=\"https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/AC14_Group_Photo-800x533.jpg\" alt=\"\" width=\"800\" height=\"533\" srcset=\"https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/AC14_Group_Photo-200x133.jpg 200w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/AC14_Group_Photo-300x200.jpg 300w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/AC14_Group_Photo-400x267.jpg 400w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/AC14_Group_Photo-500x333.jpg 500w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/AC14_Group_Photo-600x400.jpg 600w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/AC14_Group_Photo-700x467.jpg 700w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/AC14_Group_Photo-768x512.jpg 768w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/AC14_Group_Photo-800x533.jpg 800w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/AC14_Group_Photo-1024x683.jpg 1024w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/AC14_Group_Photo-1200x800.jpg 1200w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/AC14_Group_Photo-1536x1024.jpg 1536w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><p id=\"caption-attachment-20825\" class=\"wp-caption-text\"><em>Teilnehmer der vierzehnten Sitzung des Beratenden Ausschusses des ACAP in Lima, Peru.<br \/>\nS\u00fcdafrikas Mitglied, Dr. Azwianewi Makhado, ist der Vierte von rechts in der ersten Reihe; Foto vom ACAP-Sekretariat <\/em><\/p><\/div>  Die Entscheidung des AC14, die \u00dcberpr\u00fcfung vorzunehmen, wurde durch das Informationspapier S\u00fcdafrikas (<strong><a href=\"https:\/\/www.acap.aq\/documents\/working-groups\/population-and-conservation-status-working-group\/pacswg8\/pacswg8-information-papers\/4737-pacswg8-inf-07-mouse-free-marion-mfm-project\/file\" target=\"_blank\" rel=\"noopener\">PaCSWG8 Inf 07)<\/a><\/strong> an die Arbeitsgruppe, in dem \u00fcber die Fortschritte mit dem Mouse-Free Marion (<strong><a href=\"https:\/\/mousefreemarion.org\/\" target=\"_blank\" rel=\"noopener\">MFM<\/a><\/strong>) Projekt (<strong><a href=\"https:\/\/mousefreemarion.org\/the-albatross-and-petrel-agreement-renews-its-support-for-south-africas-mouse-free-marion-project-at-its-2024-meetings\/\" target=\"_blank\" rel=\"noopener\">klicken Sie hier<\/a><\/strong>) und eine Erkl\u00e4rung des Vereinigten K\u00f6nigreichs in seinem Bericht (siehe AC14 6.10) an die Arbeitsgruppe, in der es \u00fcber den aktuellen Stand der Untersuchungen des Royal Society for the Protection of Bird&#8217;s <strong><a href=\"https:\/\/www.goughisland.com\/\" target=\"_blank\" rel=\"noopener\">Gough Island Wiederherstellungsprogramm<\/a><\/strong> \u00fcber das j\u00fcngste Scheitern der Ausrottung von Hausm\u00e4usen auf dieser Insel.<br \/>\nS\u00fcdafrika wird \u00fcber sein nationales Mitglied in der PaCSWG, Dr. Azwianewi (Newi) Makhado, an der geplanten \u00dcberpr\u00fcfung der Ausrottungsrichtlinien w\u00e4hrend der Sitzungsperiode teilnehmen.<strong><a href=\"https:\/\/www.dffe.gov.za\/OceansandCoasts\" target=\"_blank\" rel=\"noopener\">Ozeane und K\u00fcsten, Ministerium f\u00fcr Forstwirtschaft, Fischerei und Umwelt<\/a><\/strong>).<br \/>\nDas MFM-Projekt wird Newi bei diesem Vorhaben unterst\u00fctzen und so dazu beitragen, dass die Richtlinien die Probleme im Zusammenhang mit der Ausrottung der Hausm\u00e4use auf den Inseln besonders ber\u00fccksichtigen, insbesondere dort, wo sie der einzige terrestrische R\u00e4uber sind und auf Seev\u00f6gel umgestiegen sind, wie auf Gough und Marion.<br \/>\nDie laufenden Feldforschungen des MFM-Projekts auf Marion Island, einschlie\u00dflich der Pl\u00e4ne f\u00fcr einen K\u00f6derversuch aus der Luft im Jahr 2026, werden dazu beitragen, die Empfehlungen des Leitfadens f\u00fcr geplante und k\u00fcnftige Projekte zur M\u00e4useausrottung zu formulieren. <strong>Referenzen:<\/strong> Beratender Ausschuss, Sekretariat 2024. <strong><a href=\"https:\/\/www.acap.aq\/documents\/advisory-committee\/ac14\/ac14-meeting-documents\/4758-ac14-doc-22-ac-work-programme-2023-2025\/file\" target=\"_blank\" rel=\"noopener\"><em>Arbeitsprogramm des Beratenden Ausschusses 2023-2025<\/em><\/a><\/strong>.<br \/>\nVierzehnte Sitzung des Beratenden Ausschusses, Lima, Peru, 12-16 August 2024.<br \/>\nAC14 Doc 22.<br \/>\n15 Seiten.       Abkommen \u00fcber die Erhaltung der Albatrosse und Sturmv\u00f6gel 2024. <strong><a href=\"https:\/\/www.acap.aq\/documents\/advisory-committee\/ac14\/4851-ac14-report\/file\" target=\"_blank\" rel=\"noopener\"><em>Bericht der vierzehnten Sitzung des Beratenden Ausschusses, Lima, Peru, 14-16 August 2024<\/em><\/a><\/strong><em>. <\/em> 92 Seiten.<br \/>\nPhillips, R.A. 2019. <strong><a href=\"https:\/\/www.acap.aq\/resources\/acap-conservation-guidelines\/2179-eradication-guidelines\/file\" target=\"_blank\" rel=\"noopener\"><em>Leitlinien f\u00fcr die Ausrottung eingeschleppter S\u00e4ugetiere aus Brutgebieten von ACAP-gelisteten Seev\u00f6geln<\/em><\/a><\/strong>.<br \/>\nAbkommen \u00fcber die Erhaltung der Albatrosse und Sturmv\u00f6gel.<br \/>\n10 Seiten.<br \/>\nArbeitsgruppe Population und Erhaltungszustand 2024<em>. <\/em><strong><a href=\"https:\/\/www.acap.aq\/documents\/advisory-committee\/ac14\/ac14-meeting-documents\/4834-ac14-doc-14\/file\" target=\"_blank\" rel=\"noopener\"><em>Bericht der Arbeitsgruppe f\u00fcr Population und Erhaltungsstatus<\/em><\/a><\/strong>.<br \/>\nVierzehntes Treffen des Beratenden Ausschusses, Lima, Peru, 12-16 August 2024.<br \/>\nAC14 Doc 14 Rev 2.<br \/>\n41 Seiten.<br \/>\nWolfaardt, A. &amp; Makhado, A. 2024. <strong><a href=\"https:\/\/www.acap.aq\/documents\/working-groups\/population-and-conservation-status-working-group\/pacswg8\/pacswg8-information-papers\/4737-pacswg8-inf-07-mouse-free-marion-mfm-project\/file\" target=\"_blank\" rel=\"noopener\"><em>Ein Update zum Projekt Mouse-Free Marion (MFM)<\/em><\/a><\/strong>.<br \/>\nAchte Sitzung der Population and Conservation Status Working Group, Lima, Peru, 9. August 2024.<br \/>\nPaCSWG8 Inf 07.           3 Seiten. &nbsp;<em>John Cooper, Nachrichtenkorrespondent, Mouse-Free Marion Project, 25. September 2023<\/em> ******************************************************************************** <div id=\"attachment_20830\" style=\"width: 810px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" aria-describedby=\"caption-attachment-20830\" class=\"wp-image-20830 size-fusion-800\" src=\"https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/preview_sooty_eng-800x1207.jpg\" alt=\"\" width=\"800\" height=\"1207\" srcset=\"https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/preview_sooty_eng-199x300.jpg 199w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/preview_sooty_eng-200x302.jpg 200w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/preview_sooty_eng-400x604.jpg 400w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/preview_sooty_eng-500x754.jpg 500w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/preview_sooty_eng-600x905.jpg 600w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/preview_sooty_eng-679x1024.jpg 679w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/preview_sooty_eng-700x1056.jpg 700w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/preview_sooty_eng-768x1159.jpg 768w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/preview_sooty_eng-800x1207.jpg 800w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/preview_sooty_eng-1018x1536.jpg 1018w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/preview_sooty_eng-1200x1811.jpg 1200w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/preview_sooty_eng-1357x2048.jpg 1357w, https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/preview_sooty_eng-scaled.jpg 1697w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><p id=\"caption-attachment-20830\" class=\"wp-caption-text\"><em><strong><a href=\"https:\/\/datazone.birdlife.org\/species\/factsheet\/sooty-albatross-phoebetria-fusca\/text\" target=\"_blank\" rel=\"noopener\">Vom Aussterben bedroht<\/a><\/strong> Ru\u00dfalbatrosse br\u00fcten auf Marion Island, wo sie durch Angriffe der eingeschleppten Hausm\u00e4use gef\u00e4hrdet sind; Infoposter des Abkommens zur Erhaltung der Albatrosse und Sturmv\u00f6gel<\/em><\/p><\/div> Das Mouse-Free Marion Project ist eine in S\u00fcdafrika eingetragene gemeinn\u00fctzige Gesellschaft (Nr. 2020\/922433\/08), die gegr\u00fcndet wurde, um die invasiven, Albatrosse t\u00f6tenden M\u00e4use auf Marion Island im S\u00fcdpolarmeer auszurotten. Das Projekt wurde initiiert von <strong><a href=\"https:\/\/www.birdlife.org.za\/\" target=\"_blank\" rel=\"noopener\">BirdLife S\u00fcdafrika<\/a><\/strong> und dem s\u00fcdafrikanischen <strong><a href=\"https:\/\/www.dffe.gov.za\/\" target=\"_blank\" rel=\"noopener\">Ministerium f\u00fcr Forstwirtschaft, Fischerei und Umwelt<\/a><\/strong>. Nach erfolgreichem Abschluss wird das Projekt den kritischen Bruthabitat von \u00fcber zwei Millionen Seev\u00f6geln, von denen viele weltweit bedroht sind, wiederherstellen und die Widerstandsf\u00e4higkeit der Insel gegen\u00fcber der Klimaerw\u00e4rmung verbessern. F\u00fcr weitere Informationen oder zur Unterst\u00fctzung des Projekts besuchen Sie bitte <strong><a href=\"http:\/\/mousefreemarion.org\/\" target=\"_blank\" rel=\"noopener\">mousefreemarion.org<\/a><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bild oben: Dieses Jungtier des Hellmantelalbatros hat die n\u00e4chtlichen Angriffe  [&#8230;]<\/p>\n","protected":false},"author":5,"featured_media":20837,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-20841","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00fcdafrika wird das Albatros- und Sturmvogelabkommen bei der \u00dcberarbeitung seiner Best-Practice-Richtlinien f\u00fcr die Ausrottung eingeschleppter S\u00e4ugetiere auf Inseln unterst\u00fctzen - Mouse-Free Marion<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mousefreemarion.org\/de\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00fcdafrika wird das Albatros- und Sturmvogelabkommen bei der \u00dcberarbeitung seiner Best-Practice-Richtlinien f\u00fcr die Ausrottung eingeschleppter S\u00e4ugetiere auf Inseln unterst\u00fctzen - Mouse-Free Marion\" \/>\n<meta property=\"og:description\" content=\"Bild oben: Dieses Jungtier des Hellmantelalbatros hat die n\u00e4chtlichen Angriffe [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mousefreemarion.org\/de\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\/\" \/>\n<meta property=\"og:site_name\" content=\"Mouse-Free Marion\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-25T11:49:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/Light-mantled-Albatross-Peter-Ryan-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"John Cooper\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"John Cooper\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\\\/\"},\"author\":{\"name\":\"John Cooper\",\"@id\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/#\\\/schema\\\/person\\\/e954c509ad876f56a7ef9755e61dbe14\"},\"headline\":\"S\u00fcdafrika wird das Albatros- und Sturmvogelabkommen bei der \u00dcberarbeitung seiner Best-Practice-Richtlinien f\u00fcr die Ausrottung eingeschleppter S\u00e4ugetiere auf Inseln unterst\u00fctzen\",\"datePublished\":\"2024-09-25T11:49:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\\\/\"},\"wordCount\":710,\"image\":{\"@id\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mousefreemarion.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Light-mantled-Albatross-Peter-Ryan-scaled.jpg\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\\\/\",\"url\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\\\/\",\"name\":\"S\u00fcdafrika wird das Albatros- und Sturmvogelabkommen bei der \u00dcberarbeitung seiner Best-Practice-Richtlinien f\u00fcr die Ausrottung eingeschleppter S\u00e4ugetiere auf Inseln unterst\u00fctzen - Mouse-Free Marion\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mousefreemarion.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Light-mantled-Albatross-Peter-Ryan-scaled.jpg\",\"datePublished\":\"2024-09-25T11:49:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/#\\\/schema\\\/person\\\/e954c509ad876f56a7ef9755e61dbe14\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mousefreemarion.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Light-mantled-Albatross-Peter-Ryan-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mousefreemarion.org\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Light-mantled-Albatross-Peter-Ryan-scaled.jpg\",\"width\":2560,\"height\":1853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/kampagne-zur-erhaltung-der-natur\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00fcdafrika wird das Albatros- und Sturmvogelabkommen bei der \u00dcberarbeitung seiner Best-Practice-Richtlinien f\u00fcr die Ausrottung eingeschleppter S\u00e4ugetiere auf Inseln unterst\u00fctzen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/\",\"name\":\"Mouse-Free Marion\",\"description\":\"Mouse-Free Marion\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/#\\\/schema\\\/person\\\/e954c509ad876f56a7ef9755e61dbe14\",\"name\":\"John Cooper\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97d75e64d53ed4e43c3caf15fb32bfe12b2d3e4a90c9e7012722c1fa159175c9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97d75e64d53ed4e43c3caf15fb32bfe12b2d3e4a90c9e7012722c1fa159175c9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/97d75e64d53ed4e43c3caf15fb32bfe12b2d3e4a90c9e7012722c1fa159175c9?s=96&d=mm&r=g\",\"caption\":\"John Cooper\"},\"url\":\"https:\\\/\\\/mousefreemarion.org\\\/de\\\/author\\\/john\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00fcdafrika wird das Albatros- und Sturmvogelabkommen bei der \u00dcberarbeitung seiner Best-Practice-Richtlinien f\u00fcr die Ausrottung eingeschleppter S\u00e4ugetiere auf Inseln unterst\u00fctzen - Mouse-Free Marion","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mousefreemarion.org\/de\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\/","og_locale":"de_DE","og_type":"article","og_title":"S\u00fcdafrika wird das Albatros- und Sturmvogelabkommen bei der \u00dcberarbeitung seiner Best-Practice-Richtlinien f\u00fcr die Ausrottung eingeschleppter S\u00e4ugetiere auf Inseln unterst\u00fctzen - Mouse-Free Marion","og_description":"Bild oben: Dieses Jungtier des Hellmantelalbatros hat die n\u00e4chtlichen Angriffe [...]","og_url":"https:\/\/mousefreemarion.org\/de\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\/","og_site_name":"Mouse-Free Marion","article_published_time":"2024-09-25T11:49:57+00:00","og_image":[{"width":2560,"height":1853,"url":"https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/Light-mantled-Albatross-Peter-Ryan-scaled.jpg","type":"image\/jpeg"}],"author":"John Cooper","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"John Cooper","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mousefreemarion.org\/de\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\/#article","isPartOf":{"@id":"https:\/\/mousefreemarion.org\/de\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\/"},"author":{"name":"John Cooper","@id":"https:\/\/mousefreemarion.org\/de\/#\/schema\/person\/e954c509ad876f56a7ef9755e61dbe14"},"headline":"S\u00fcdafrika wird das Albatros- und Sturmvogelabkommen bei der \u00dcberarbeitung seiner Best-Practice-Richtlinien f\u00fcr die Ausrottung eingeschleppter S\u00e4ugetiere auf Inseln unterst\u00fctzen","datePublished":"2024-09-25T11:49:57+00:00","mainEntityOfPage":{"@id":"https:\/\/mousefreemarion.org\/de\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\/"},"wordCount":710,"image":{"@id":"https:\/\/mousefreemarion.org\/de\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\/#primaryimage"},"thumbnailUrl":"https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/Light-mantled-Albatross-Peter-Ryan-scaled.jpg","articleSection":["Unkategorisiert"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/mousefreemarion.org\/de\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\/","url":"https:\/\/mousefreemarion.org\/de\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\/","name":"S\u00fcdafrika wird das Albatros- und Sturmvogelabkommen bei der \u00dcberarbeitung seiner Best-Practice-Richtlinien f\u00fcr die Ausrottung eingeschleppter S\u00e4ugetiere auf Inseln unterst\u00fctzen - Mouse-Free Marion","isPartOf":{"@id":"https:\/\/mousefreemarion.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mousefreemarion.org\/de\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\/#primaryimage"},"image":{"@id":"https:\/\/mousefreemarion.org\/de\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\/#primaryimage"},"thumbnailUrl":"https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/Light-mantled-Albatross-Peter-Ryan-scaled.jpg","datePublished":"2024-09-25T11:49:57+00:00","author":{"@id":"https:\/\/mousefreemarion.org\/de\/#\/schema\/person\/e954c509ad876f56a7ef9755e61dbe14"},"breadcrumb":{"@id":"https:\/\/mousefreemarion.org\/de\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mousefreemarion.org\/de\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mousefreemarion.org\/de\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\/#primaryimage","url":"https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/Light-mantled-Albatross-Peter-Ryan-scaled.jpg","contentUrl":"https:\/\/mousefreemarion.org\/wp-content\/uploads\/2024\/09\/Light-mantled-Albatross-Peter-Ryan-scaled.jpg","width":2560,"height":1853},{"@type":"BreadcrumbList","@id":"https:\/\/mousefreemarion.org\/de\/suedafrika-wird-das-albatros-und-sturmvogelabkommen-bei-der-ueberarbeitung-seiner-best-practice-richtlinien-fuer-die-ausrottung-eingeschleppter-saeugetiere-auf-inseln-unterstuetzen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mousefreemarion.org\/de\/kampagne-zur-erhaltung-der-natur\/"},{"@type":"ListItem","position":2,"name":"S\u00fcdafrika wird das Albatros- und Sturmvogelabkommen bei der \u00dcberarbeitung seiner Best-Practice-Richtlinien f\u00fcr die Ausrottung eingeschleppter S\u00e4ugetiere auf Inseln unterst\u00fctzen"}]},{"@type":"WebSite","@id":"https:\/\/mousefreemarion.org\/de\/#website","url":"https:\/\/mousefreemarion.org\/de\/","name":"Mouse-Free Marion","description":"Mouse-Free Marion","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mousefreemarion.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/mousefreemarion.org\/de\/#\/schema\/person\/e954c509ad876f56a7ef9755e61dbe14","name":"John Cooper","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/97d75e64d53ed4e43c3caf15fb32bfe12b2d3e4a90c9e7012722c1fa159175c9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/97d75e64d53ed4e43c3caf15fb32bfe12b2d3e4a90c9e7012722c1fa159175c9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/97d75e64d53ed4e43c3caf15fb32bfe12b2d3e4a90c9e7012722c1fa159175c9?s=96&d=mm&r=g","caption":"John Cooper"},"url":"https:\/\/mousefreemarion.org\/de\/author\/john\/"}]}},"_links":{"self":[{"href":"https:\/\/mousefreemarion.org\/de\/wp-json\/wp\/v2\/posts\/20841","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mousefreemarion.org\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mousefreemarion.org\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mousefreemarion.org\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/mousefreemarion.org\/de\/wp-json\/wp\/v2\/comments?post=20841"}],"version-history":[{"count":0,"href":"https:\/\/mousefreemarion.org\/de\/wp-json\/wp\/v2\/posts\/20841\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mousefreemarion.org\/de\/wp-json\/wp\/v2\/media\/20837"}],"wp:attachment":[{"href":"https:\/\/mousefreemarion.org\/de\/wp-json\/wp\/v2\/media?parent=20841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mousefreemarion.org\/de\/wp-json\/wp\/v2\/categories?post=20841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mousefreemarion.org\/de\/wp-json\/wp\/v2\/tags?post=20841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}